{"id":522,"date":"2017-12-18T13:50:06","date_gmt":"2017-12-18T12:50:06","guid":{"rendered":"http:\/\/stadt-adventskalender.de\/museumsinsel\/?page_id=522"},"modified":"2017-12-21T00:17:12","modified_gmt":"2017-12-20T23:17:12","slug":"quellen","status":"publish","type":"page","link":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/quellen\/","title":{"rendered":"Quellen"},"content":{"rendered":"<p>Quellenangaben<\/p>\n<p>http:\/\/www.bibelwissenschaft.de<br \/>\nhttp:\/\/berliner-schloss.de\/blog\/der-omphalos-und-der-neptunbrunnen\/ https:\/\/www.berliner-zeitung.de\/25003200 \u00a92017<br \/>\nhttps:\/\/de.wikipedia.org\/wiki\/Lustgarten_(Berlin)<br \/>\nhttps:\/\/www.centrumjudaicum.de<br \/>\nhttps:\/\/de.wikipedia.org\/wiki\/Neue_Synagoge_(Berlin)<br \/>\nIm j\u00fcdischen Leben, Die Erinnerungen des Berliner Rabbiners Malwin Warschauer; :TRANSIT Buchverlag, 1995<br \/>\nhttp:\/\/www.ballhaus.de\/<br \/>\nhttp:\/\/www.bz-berlin.de<br \/>\nhttps:\/\/www.stadtmuseum.de\/objekte-und-geschichten\/ernst-litfass-nachlass<br \/>\nhttp:\/\/www.markuskappeler.ch\/tex\/texs\/humboldtpinguin.html<br \/>\nhttps:\/\/de.wikipedia.org\/wiki\/Adelbert_von_Chamisso<br \/>\nVoss, Kaja Die Museumsinsel, Gescgichte und Gegenwart, be.bra verlag, 2011<br \/>\nSteffens, Martin, Schinkel, TASCHEN, 2003<br \/>\nhttp:\/\/www.stadtentwicklung.berlin.de, tapetenkunst.de<br \/>\nraumzeichner.de\/moderne-materialien-denkmalpflege\/<br \/>\nhttps:\/\/www.morgenpost.de<br \/>\nDIE WELT: Tod aus dem Osten<br \/>\nBorchert, J\u00fcrgen: Die Zusammenarbeit des Ministeriums f\u00fcr Staatssicherheit (MfS) mit dem sowjetischen KGB in den 70er und 80er Jahren: https:\/\/www.morgenpost.de\/printarchiv\/berlin\/article104521266\/Rohrpost-sauste-pro-Sekunde-15-Meter.html<br \/>\nhttps:\/\/www.berlin.de\/sehenswuerdigkeiten\/3560037-3558930-lustgarten.html<br \/>\nhttp:\/\/www.luise-berlin.de\/stadtentwicklung\/texte\/2_03_lustgarten.htm<br \/>\nhttps:\/\/www.stiftung-stmatthaeus.de\/veranstaltung\/kanzel-der-st-marienkirche\/<br \/>\nhttps:\/\/thruttig.wordpress.com<br \/>\nFrank Joachim, \u00c4gyptologe<br \/>\nhttp:\/\/www.spiegel.de\/spiegelgeschichte\/ischtar-tor-in-berlin-sternstunde-deutscher-archaeologie-a-1084890.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quellenangaben http:\/\/www.bibelwissenschaft.de http:\/\/berliner-schloss.de\/blog\/der-omphalos-und-der-neptunbrunnen\/ https:\/\/www.berliner-zeitung.de\/25003200 \u00a92017 https:\/\/de.wikipedia.org\/wiki\/Lustgarten_(Berlin) https:\/\/www.centrumjudaicum.de https:\/\/de.wikipedia.org\/wiki\/Neue_Synagoge_(Berlin) Im j\u00fcdischen Leben, Die Erinnerungen des Berliner Rabbiners Malwin Warschauer; :TRANSIT Buchverlag, 1995 http:\/\/www.ballhaus.de\/ http:\/\/www.bz-berlin.de https:\/\/www.stadtmuseum.de\/objekte-und-geschichten\/ernst-litfass-nachlass http:\/\/www.markuskappeler.ch\/tex\/texs\/humboldtpinguin.html https:\/\/de.wikipedia.org\/wiki\/Adelbert_von_Chamisso Voss, Kaja Die Museumsinsel, Gescgichte und Gegenwart, be.bra verlag, 2011 Steffens, Martin, Schinkel, TASCHEN, 2003 http:\/\/www.stadtentwicklung.berlin.de, tapetenkunst.de raumzeichner.de\/moderne-materialien-denkmalpflege\/ https:\/\/www.morgenpost.de DIE WELT: Tod aus dem Osten Borchert, J\u00fcrgen: Die Zusammenarbeit &hellip; <a href=\"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/quellen\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Quellen<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-522","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:11:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/pages\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/comments?post=522"}],"version-history":[{"count":8,"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/pages\/522\/revisions"}],"predecessor-version":[{"id":655,"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/pages\/522\/revisions\/655"}],"wp:attachment":[{"href":"https:\/\/stadt-adventskalender.de\/museumsinsel\/en\/wp-json\/wp\/v2\/media?parent=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}